{"id":48,"date":"2006-08-08T19:51:08","date_gmt":"2006-08-08T19:51:08","guid":{"rendered":"https:\/\/bobsmile.wordpress.com\/2006\/08\/08\/der-bauch-muss-weg\/"},"modified":"2006-08-08T19:51:08","modified_gmt":"2006-08-08T19:51:08","slug":"der-bauch-muss-weg","status":"publish","type":"post","link":"http:\/\/www.bobsmile.ch\/wordpress\/2006\/08\/08\/der-bauch-muss-weg\/","title":{"rendered":"Der Bauch muss weg!"},"content":{"rendered":"<p>Eigentlich wollte ich was zu Floyd Landis schreiben, der nach seiner einwandfreien \u00dcberf\u00fchrung etwas arg naiv mit absurden Verschw\u00f6hrungstheorien um sich schmeisst.<\/p>\n<p>&#8222;Mein Ziel ist es, meine Unschuld zu beweisen&#8220;, sagte der 30-J\u00e4hrige in einem Interview mit <a href=\"http:\/\/www.usatoday.com\/sports\/cycling\/2006-08-06-landis-retort_x.htm\" title=\"Floyd Landis' Verschw\u00f6rungstheorie\">-&gt; USA Today<\/a>. Na, da wird er ja wohl jetzt auch jede Menge Zeit dazu haben&#8230;<\/p>\n<p>Der richtige Zeitpunkt um \u00fcber die eigene Fitness nachzudenken, denn <i>bobsmiles <\/i>Bauch ist nach den Sommerferien merklich runder geworden und eine gewisse Tr\u00e4gheit macht sich bei ihm breit.<br \/>\nAlso, rein in die Joggingschuhe und los gehts. Nachfolgend sind in lockerer Form die Trainingsergebnisse der laufenden Woche aufgelistet:<\/p>\n<p>Anfangsgewicht: 79.7 kg<\/p>\n<p>Montag :   2000 Schritte auf dem Step : 14&#8242; 34&#8220;<br \/>\nDienstag : Rundlauf durch den Buchsiwald : 27&#8242; 21&#8220;<br \/>\nMittwoch : FDH, na immer hin!<br \/>\nDonnerstag : Rundlauf durch den Buchsiwald : 25.35&#8243; (aha)<br \/>\nFreitag : FDH<br \/>\nSamstag \/ Sonntag : \u00e4h, vergessen ?<\/p>\n<p>Gewicht nach einer Woche: 78.3 kg.<br \/>\nJetzt passt bobsmile so langsam wieder ins Lederkombi&#8230; \ud83d\ude42<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eigentlich wollte ich was zu Floyd Landis schreiben, der nach seiner einwandfreien \u00dcberf\u00fchrung etwas arg naiv mit absurden Verschw\u00f6hrungstheorien um sich schmeisst. &#8222;Mein Ziel ist es, meine Unschuld zu beweisen&#8220;, sagte der 30-J\u00e4hrige in einem Interview mit -&gt; USA Today. Na, da wird er ja wohl jetzt auch jede Menge Zeit dazu haben&#8230; Der richtigeContinue reading &rarr;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,18],"tags":[],"_links":{"self":[{"href":"http:\/\/www.bobsmile.ch\/wordpress\/wp-json\/wp\/v2\/posts\/48"}],"collection":[{"href":"http:\/\/www.bobsmile.ch\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.bobsmile.ch\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.bobsmile.ch\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.bobsmile.ch\/wordpress\/wp-json\/wp\/v2\/comments?post=48"}],"version-history":[{"count":0,"href":"http:\/\/www.bobsmile.ch\/wordpress\/wp-json\/wp\/v2\/posts\/48\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.bobsmile.ch\/wordpress\/wp-json\/wp\/v2\/media?parent=48"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.bobsmile.ch\/wordpress\/wp-json\/wp\/v2\/categories?post=48"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.bobsmile.ch\/wordpress\/wp-json\/wp\/v2\/tags?post=48"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}